{"id":52816,"date":"2026-04-12T09:47:20","date_gmt":"2026-04-12T07:47:20","guid":{"rendered":"https:\/\/dev6.erresse-shop.it\/shop\/unkategorisiert\/illy-iperespresso-experience-kit-2er-set-tassen-mit-untertasse-und-loeffel\/"},"modified":"2025-07-03T20:54:37","modified_gmt":"2025-07-03T18:54:37","slug":"illy-iperespresso-experience-kit-2er-set-tassen-mit-untertasse-und-loeffel","status":"publish","type":"product","link":"https:\/\/dev6.erresse-shop.it\/de\/shop\/tisch\/tassen\/illy-iperespresso-experience-kit-2er-set-tassen-mit-untertasse-und-loeffel\/","title":{"rendered":"ILLY  Iperespresso Experience Kit 2er-Set Tassen mit Untertasse und L\u00f6ffel"},"content":{"rendered":"<p>Die Box \u201cIperespresso experience kit\u201d soll das Kaffeetrinken zu Hause zu einem besonderen Erlebnis machen. Das Set enth\u00e4lt zwei Tassen und zwei Espressotassen aus Luxion\u00ae, die von Matteo Thun entworfen wurden und die Crema des Espressos durch ein Spiel mit der Transparenz optimal zur Geltung bringen und zusammen mit den 2 Designer-Edelstahll\u00f6ffeln zu einem einzigartigen Geschmackserlebnis beitragen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Box \u201cIperespresso experience kit\u201d soll das Kaffeetrinken zu Hause zu einem besonderen Erlebnis machen. Das Set enth\u00e4lt zwei Tassen und zwei Espressotassen aus Luxion\u00ae, die von Matteo Thun entworfen wurden und die Crema des Espressos durch ein Spiel mit der Transparenz optimal zur Geltung bringen und zusammen mit den 2 Designer-Edelstahll\u00f6ffeln zu einem einzigartigen [&hellip;]<\/p>\n","protected":false},"featured_media":6363089,"template":"","meta":{"_acf_changed":false},"product_cat":[12121,11671,12103],"product_tag":[],"class_list":{"0":"post-52816","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-tassen","7":"product_cat-tavola","8":"product_cat-tisch","10":"first","11":"instock","12":"sale","13":"taxable","14":"shipping-taxable","15":"purchasable","16":"product-type-simple","swatches":"rey-swatches","show_selected":"","stretch_labels":"rey-swatches--stretch-labels"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>ILLY Iperespresso Experience Kit 2er-Set Tassen mit Untertasse und L\u00f6ffel - dev6 Erresse<\/title>\n<meta name=\"description\" content=\"Die Box \u201cIperespresso experience kit\u201d soll das Kaffeetrinken zu Hause zu einem besonderen Erlebnis machen. Das Set enth\u00e4lt zwei Tassen und zwei\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ILLY Iperespresso Experience Kit 2er-Set Tassen mit Untertasse und L\u00f6ffel - dev6 Erresse\" \/>\n<meta property=\"og:description\" content=\"Die Box \u201cIperespresso experience kit\u201d soll das Kaffeetrinken zu Hause zu einem besonderen Erlebnis machen. Das Set enth\u00e4lt zwei Tassen und zwei\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev6.erresse-shop.it\/de\/shop\/tisch\/tassen\/illy-iperespresso-experience-kit-2er-set-tassen-mit-untertasse-und-loeffel\/\" \/>\n<meta property=\"og:site_name\" content=\"dev6 Erresse\" \/>\n<meta property=\"og:image\" content=\"https:\/\/interpim.erresse-shop.it\/Import\/Prodotti\/illy-iperespresso-experience-kit-set-2-tazzine-con-piattino-e-cucchiaini.jpg\" \/><meta property=\"og:image\" content=\"https:\/\/interpim.erresse-shop.it\/Import\/Prodotti\/illy-iperespresso-experience-kit-set-2-tazzine-con-piattino-e-cucchiaini.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/interpim.erresse-shop.it\/Import\/Prodotti\/illy-iperespresso-experience-kit-set-2-tazzine-con-piattino-e-cucchiaini.jpg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dev6.erresse-shop.it\/de\/shop\/tisch\/tassen\/illy-iperespresso-experience-kit-2er-set-tassen-mit-untertasse-und-loeffel\/\",\"url\":\"https:\/\/dev6.erresse-shop.it\/de\/shop\/tisch\/tassen\/illy-iperespresso-experience-kit-2er-set-tassen-mit-untertasse-und-loeffel\/\",\"name\":\"ILLY Iperespresso Experience Kit 2er-Set Tassen mit Untertasse und L\u00f6ffel - dev6 Erresse\",\"isPartOf\":{\"@id\":\"https:\/\/dev6.erresse-shop.it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dev6.erresse-shop.it\/de\/shop\/tisch\/tassen\/illy-iperespresso-experience-kit-2er-set-tassen-mit-untertasse-und-loeffel\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dev6.erresse-shop.it\/de\/shop\/tisch\/tassen\/illy-iperespresso-experience-kit-2er-set-tassen-mit-untertasse-und-loeffel\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/i0.wp.com\/interpim.erresse-shop.it\/Import\/Prodotti\/illy-iperespresso-experience-kit-set-2-tazzine-con-piattino-e-cucchiaini.jpg?ssl=1\",\"datePublished\":\"2026-04-12T07:47:20+00:00\",\"description\":\"Die Box \u201cIperespresso experience kit\u201d soll das Kaffeetrinken zu Hause zu einem besonderen Erlebnis machen. Das Set enth\u00e4lt zwei Tassen und zwei\",\"breadcrumb\":{\"@id\":\"https:\/\/dev6.erresse-shop.it\/de\/shop\/tisch\/tassen\/illy-iperespresso-experience-kit-2er-set-tassen-mit-untertasse-und-loeffel\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dev6.erresse-shop.it\/de\/shop\/tisch\/tassen\/illy-iperespresso-experience-kit-2er-set-tassen-mit-untertasse-und-loeffel\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/dev6.erresse-shop.it\/de\/shop\/tisch\/tassen\/illy-iperespresso-experience-kit-2er-set-tassen-mit-untertasse-und-loeffel\/#primaryimage\",\"url\":\"https:\/\/i0.wp.com\/interpim.erresse-shop.it\/Import\/Prodotti\/illy-iperespresso-experience-kit-set-2-tazzine-con-piattino-e-cucchiaini.jpg?ssl=1\",\"contentUrl\":\"https:\/\/i0.wp.com\/interpim.erresse-shop.it\/Import\/Prodotti\/illy-iperespresso-experience-kit-set-2-tazzine-con-piattino-e-cucchiaini.jpg?ssl=1\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dev6.erresse-shop.it\/de\/shop\/tisch\/tassen\/illy-iperespresso-experience-kit-2er-set-tassen-mit-untertasse-und-loeffel\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/dev6.erresse-shop.it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/dev6.erresse-shop.it\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"ILLY Iperespresso Experience Kit 2er-Set Tassen mit Untertasse und L\u00f6ffel\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dev6.erresse-shop.it\/#website\",\"url\":\"https:\/\/dev6.erresse-shop.it\/\",\"name\":\"Erresse Shop\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/dev6.erresse-shop.it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dev6.erresse-shop.it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/dev6.erresse-shop.it\/#organization\",\"name\":\"Erresse Shop\",\"url\":\"https:\/\/dev6.erresse-shop.it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/dev6.erresse-shop.it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dev6.erresse-shop.it\/wp-content\/uploads\/2025\/01\/LOGO-ERRESSE-CLASSICO.svg\",\"contentUrl\":\"https:\/\/dev6.erresse-shop.it\/wp-content\/uploads\/2025\/01\/LOGO-ERRESSE-CLASSICO.svg\",\"caption\":\"Erresse Shop\"},\"image\":{\"@id\":\"https:\/\/dev6.erresse-shop.it\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ILLY Iperespresso Experience Kit 2er-Set Tassen mit Untertasse und L\u00f6ffel - dev6 Erresse","description":"Die Box \u201cIperespresso experience kit\u201d soll das Kaffeetrinken zu Hause zu einem besonderen Erlebnis machen. Das Set enth\u00e4lt zwei Tassen und zwei","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"de_DE","og_type":"article","og_title":"ILLY Iperespresso Experience Kit 2er-Set Tassen mit Untertasse und L\u00f6ffel - dev6 Erresse","og_description":"Die Box \u201cIperespresso experience kit\u201d soll das Kaffeetrinken zu Hause zu einem besonderen Erlebnis machen. Das Set enth\u00e4lt zwei Tassen und zwei","og_url":"https:\/\/dev6.erresse-shop.it\/de\/shop\/tisch\/tassen\/illy-iperespresso-experience-kit-2er-set-tassen-mit-untertasse-und-loeffel\/","og_site_name":"dev6 Erresse","og_image":[{"url":"https:\/\/interpim.erresse-shop.it\/Import\/Prodotti\/illy-iperespresso-experience-kit-set-2-tazzine-con-piattino-e-cucchiaini.jpg","type":"","width":"","height":""},{"url":"https:\/\/interpim.erresse-shop.it\/Import\/Prodotti\/illy-iperespresso-experience-kit-set-2-tazzine-con-piattino-e-cucchiaini.jpg","width":1024,"height":1024,"type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_image":"https:\/\/interpim.erresse-shop.it\/Import\/Prodotti\/illy-iperespresso-experience-kit-set-2-tazzine-con-piattino-e-cucchiaini.jpg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dev6.erresse-shop.it\/de\/shop\/tisch\/tassen\/illy-iperespresso-experience-kit-2er-set-tassen-mit-untertasse-und-loeffel\/","url":"https:\/\/dev6.erresse-shop.it\/de\/shop\/tisch\/tassen\/illy-iperespresso-experience-kit-2er-set-tassen-mit-untertasse-und-loeffel\/","name":"ILLY Iperespresso Experience Kit 2er-Set Tassen mit Untertasse und L\u00f6ffel - dev6 Erresse","isPartOf":{"@id":"https:\/\/dev6.erresse-shop.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dev6.erresse-shop.it\/de\/shop\/tisch\/tassen\/illy-iperespresso-experience-kit-2er-set-tassen-mit-untertasse-und-loeffel\/#primaryimage"},"image":{"@id":"https:\/\/dev6.erresse-shop.it\/de\/shop\/tisch\/tassen\/illy-iperespresso-experience-kit-2er-set-tassen-mit-untertasse-und-loeffel\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/interpim.erresse-shop.it\/Import\/Prodotti\/illy-iperespresso-experience-kit-set-2-tazzine-con-piattino-e-cucchiaini.jpg?ssl=1","datePublished":"2026-04-12T07:47:20+00:00","description":"Die Box \u201cIperespresso experience kit\u201d soll das Kaffeetrinken zu Hause zu einem besonderen Erlebnis machen. Das Set enth\u00e4lt zwei Tassen und zwei","breadcrumb":{"@id":"https:\/\/dev6.erresse-shop.it\/de\/shop\/tisch\/tassen\/illy-iperespresso-experience-kit-2er-set-tassen-mit-untertasse-und-loeffel\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev6.erresse-shop.it\/de\/shop\/tisch\/tassen\/illy-iperespresso-experience-kit-2er-set-tassen-mit-untertasse-und-loeffel\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/dev6.erresse-shop.it\/de\/shop\/tisch\/tassen\/illy-iperespresso-experience-kit-2er-set-tassen-mit-untertasse-und-loeffel\/#primaryimage","url":"https:\/\/i0.wp.com\/interpim.erresse-shop.it\/Import\/Prodotti\/illy-iperespresso-experience-kit-set-2-tazzine-con-piattino-e-cucchiaini.jpg?ssl=1","contentUrl":"https:\/\/i0.wp.com\/interpim.erresse-shop.it\/Import\/Prodotti\/illy-iperespresso-experience-kit-set-2-tazzine-con-piattino-e-cucchiaini.jpg?ssl=1"},{"@type":"BreadcrumbList","@id":"https:\/\/dev6.erresse-shop.it\/de\/shop\/tisch\/tassen\/illy-iperespresso-experience-kit-2er-set-tassen-mit-untertasse-und-loeffel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dev6.erresse-shop.it\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/dev6.erresse-shop.it\/shop\/"},{"@type":"ListItem","position":3,"name":"ILLY Iperespresso Experience Kit 2er-Set Tassen mit Untertasse und L\u00f6ffel"}]},{"@type":"WebSite","@id":"https:\/\/dev6.erresse-shop.it\/#website","url":"https:\/\/dev6.erresse-shop.it\/","name":"Erresse Shop","description":"","publisher":{"@id":"https:\/\/dev6.erresse-shop.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev6.erresse-shop.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/dev6.erresse-shop.it\/#organization","name":"Erresse Shop","url":"https:\/\/dev6.erresse-shop.it\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/dev6.erresse-shop.it\/#\/schema\/logo\/image\/","url":"https:\/\/dev6.erresse-shop.it\/wp-content\/uploads\/2025\/01\/LOGO-ERRESSE-CLASSICO.svg","contentUrl":"https:\/\/dev6.erresse-shop.it\/wp-content\/uploads\/2025\/01\/LOGO-ERRESSE-CLASSICO.svg","caption":"Erresse Shop"},"image":{"@id":"https:\/\/dev6.erresse-shop.it\/#\/schema\/logo\/image\/"}}]}},"df_price":18.4,"df_sale_price":18.4,"df_regular_price":34.9,"df_image_link":"https:\/\/i0.wp.com\/interpim.erresse-shop.it\/Import\/Prodotti\/illy-iperespresso-experience-kit-set-2-tazzine-con-piattino-e-cucchiaini.jpg?resize=300,300&ssl=1","fifu_image_url":"https:\/\/interpim.erresse-shop.it\/Import\/Prodotti\/illy-iperespresso-experience-kit-set-2-tazzine-con-piattino-e-cucchiaini.jpg","_links":{"self":[{"href":"https:\/\/dev6.erresse-shop.it\/de\/wp-json\/wp\/v2\/product\/52816","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev6.erresse-shop.it\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dev6.erresse-shop.it\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev6.erresse-shop.it\/de\/wp-json\/wp\/v2\/media\/6363089"}],"wp:attachment":[{"href":"https:\/\/dev6.erresse-shop.it\/de\/wp-json\/wp\/v2\/media?parent=52816"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dev6.erresse-shop.it\/de\/wp-json\/wp\/v2\/product_cat?post=52816"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dev6.erresse-shop.it\/de\/wp-json\/wp\/v2\/product_tag?post=52816"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}